{"id":3836,"date":"2022-09-05T21:16:42","date_gmt":"2022-09-05T21:16:42","guid":{"rendered":"https:\/\/redmediterranea.com\/?p=3836"},"modified":"2022-09-05T21:16:44","modified_gmt":"2022-09-05T21:16:44","slug":"el-dia-de-las-infancia-se-festejo-en-barrio-clinicas","status":"publish","type":"post","link":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/","title":{"rendered":"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas"},"content":{"rendered":"\n<p>Con la organizaci\u00f3n de vecinos del barrio y con la colaboraci\u00f3n de la Municipalidad, los m\u00e1s peque\u00f1os pudieron disfrutar de un d\u00eda inolvidable.<br>Este a\u00f1o muchos de los ni\u00f1os no pudieron asistir al evento en el Balneario municipal por duelo; es por ello que los residentes de ese sector barrial trataron de brindar un momento especial a los chicos con juegos tradicionales, reparto de juguetes, golosinas y sorteos.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">TrabajamosConLosBarrios<\/h1>\n\n\n\n<h1 class=\"wp-block-heading\">DiaDeLasInfancias<\/h1>\n\n\n\n<h1 class=\"wp-block-heading\">GestionMabelGodoy<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Con la organizaci\u00f3n de vecinos del barrio y con la colaboraci\u00f3n de la Municipalidad, los m\u00e1s peque\u00f1os pudieron disfrutar de un d\u00eda inolvidable.Este a\u00f1o muchos de los ni\u00f1os no pudieron asistir al evento en el Balneario municipal por duelo; es por ello que los residentes de ese sector barrial trataron de brindar un momento especial [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[1327,1316],"class_list":{"0":"post-3836","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-quilino","8":"tag-barrio-clinicas","9":"tag-dia-de-las-infancias"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas &#8212; Red Mediterr\u00e1nea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas &#8212; Red Mediterr\u00e1nea\" \/>\n<meta property=\"og:description\" content=\"Con la organizaci\u00f3n de vecinos del barrio y con la colaboraci\u00f3n de la Municipalidad, los m\u00e1s peque\u00f1os pudieron disfrutar de un d\u00eda inolvidable.Este a\u00f1o muchos de los ni\u00f1os no pudieron asistir al evento en el Balneario municipal por duelo; es por ello que los residentes de ese sector barrial trataron de brindar un momento especial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Red Mediterr\u00e1nea\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redmediterranea.net\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-05T21:16:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-05T21:16:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/redmediterranea.com\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Red Mediterr\u00e1nea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Red Mediterr\u00e1nea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/\"},\"author\":{\"name\":\"Red Mediterr\u00e1nea\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/person\\\/a59f6085115b75a865fb0338fe81d577\"},\"headline\":\"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas\",\"datePublished\":\"2022-09-05T21:16:42+00:00\",\"dateModified\":\"2022-09-05T21:16:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/\"},\"wordCount\":90,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg\",\"keywords\":[\"Barrio Cl\u00ednicas\",\"D\u00eda de las infancias\"],\"articleSection\":[\"Quilino\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/\",\"name\":\"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas &#8212; Red Mediterr\u00e1nea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg\",\"datePublished\":\"2022-09-05T21:16:42+00:00\",\"dateModified\":\"2022-09-05T21:16:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg\",\"width\":864,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2022\\\/09\\\/05\\\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/redmediterranea.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#website\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/\",\"name\":\"Red Mediterr\u00e1nea\",\"description\":\"Noticias de De\u00e1n Funes\",\"publisher\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redmediterranea.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\",\"name\":\"Red Mediterr\u00e1nea\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/red.png\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/red.png\",\"width\":400,\"height\":260,\"caption\":\"Red Mediterr\u00e1nea\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redmediterranea.net\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvm4ojIMOGKnk5v9TsWnFWQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/person\\\/a59f6085115b75a865fb0338fe81d577\",\"name\":\"Red Mediterr\u00e1nea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340\",\"caption\":\"Red Mediterr\u00e1nea\"},\"sameAs\":[\"http:\\\/\\\/redmediterranea.com\"],\"url\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/author\\\/hg-hatecraft\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas &#8212; Red Mediterr\u00e1nea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/","og_locale":"es_ES","og_type":"article","og_title":"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas &#8212; Red Mediterr\u00e1nea","og_description":"Con la organizaci\u00f3n de vecinos del barrio y con la colaboraci\u00f3n de la Municipalidad, los m\u00e1s peque\u00f1os pudieron disfrutar de un d\u00eda inolvidable.Este a\u00f1o muchos de los ni\u00f1os no pudieron asistir al evento en el Balneario municipal por duelo; es por ello que los residentes de ese sector barrial trataron de brindar un momento especial [&hellip;]","og_url":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/","og_site_name":"Red Mediterr\u00e1nea","article_publisher":"https:\/\/www.facebook.com\/redmediterranea.net","article_published_time":"2022-09-05T21:16:42+00:00","article_modified_time":"2022-09-05T21:16:44+00:00","og_image":[{"width":864,"height":1152,"url":"http:\/\/redmediterranea.com\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg","type":"image\/jpeg"}],"author":"Red Mediterr\u00e1nea","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Red Mediterr\u00e1nea","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/#article","isPartOf":{"@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/"},"author":{"name":"Red Mediterr\u00e1nea","@id":"https:\/\/redmediterranea.com\/#\/schema\/person\/a59f6085115b75a865fb0338fe81d577"},"headline":"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas","datePublished":"2022-09-05T21:16:42+00:00","dateModified":"2022-09-05T21:16:44+00:00","mainEntityOfPage":{"@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/"},"wordCount":90,"commentCount":0,"publisher":{"@id":"https:\/\/redmediterranea.com\/#organization"},"image":{"@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/#primaryimage"},"thumbnailUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg","keywords":["Barrio Cl\u00ednicas","D\u00eda de las infancias"],"articleSection":["Quilino"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/","url":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/","name":"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas &#8212; Red Mediterr\u00e1nea","isPartOf":{"@id":"https:\/\/redmediterranea.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/#primaryimage"},"image":{"@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/#primaryimage"},"thumbnailUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg","datePublished":"2022-09-05T21:16:42+00:00","dateModified":"2022-09-05T21:16:44+00:00","breadcrumb":{"@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/#primaryimage","url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-05-at-4.48.47-PM.jpeg","width":864,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/redmediterranea.com\/index.php\/2022\/09\/05\/el-dia-de-las-infancia-se-festejo-en-barrio-clinicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/redmediterranea.com\/"},{"@type":"ListItem","position":2,"name":"El D\u00eda de las Infancia se festej\u00f3 en Barrio Cl\u00ednicas"}]},{"@type":"WebSite","@id":"https:\/\/redmediterranea.com\/#website","url":"https:\/\/redmediterranea.com\/","name":"Red Mediterr\u00e1nea","description":"Noticias de De\u00e1n Funes","publisher":{"@id":"https:\/\/redmediterranea.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redmediterranea.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/redmediterranea.com\/#organization","name":"Red Mediterr\u00e1nea","url":"https:\/\/redmediterranea.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/#\/schema\/logo\/image\/","url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2021\/09\/red.png","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2021\/09\/red.png","width":400,"height":260,"caption":"Red Mediterr\u00e1nea"},"image":{"@id":"https:\/\/redmediterranea.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redmediterranea.net","https:\/\/www.youtube.com\/channel\/UCvm4ojIMOGKnk5v9TsWnFWQ"]},{"@type":"Person","@id":"https:\/\/redmediterranea.com\/#\/schema\/person\/a59f6085115b75a865fb0338fe81d577","name":"Red Mediterr\u00e1nea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340","url":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340","caption":"Red Mediterr\u00e1nea"},"sameAs":["http:\/\/redmediterranea.com"],"url":"https:\/\/redmediterranea.com\/index.php\/author\/hg-hatecraft\/"}]}},"_links":{"self":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/3836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/comments?post=3836"}],"version-history":[{"count":1,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/3836\/revisions"}],"predecessor-version":[{"id":3838,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/3836\/revisions\/3838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/media\/3837"}],"wp:attachment":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/media?parent=3836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/categories?post=3836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/tags?post=3836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}