{"id":17008,"date":"2026-05-08T14:11:40","date_gmt":"2026-05-08T14:11:40","guid":{"rendered":"https:\/\/redmediterranea.com\/?p=17008"},"modified":"2026-05-08T14:11:41","modified_gmt":"2026-05-08T14:11:41","slug":"cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo","status":"publish","type":"post","link":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/","title":{"rendered":"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo\" width=\"696\" height=\"522\" src=\"https:\/\/www.youtube.com\/embed\/TJ1ldrZX5WU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"https:\/\/youtu.be\/TJ1ldrZX5WU","protected":false},"author":1,"featured_media":17009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[3,53],"tags":[279,33],"class_list":["post-17008","post","type-post","status-publish","format-video","has-post-thumbnail","category-locales","category-portada","tag-concejo-deliberante","tag-dean-funes","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo &#8212; Red Mediterr\u00e1nea<\/title>\n<meta name=\"description\" content=\"Red Mediterr\u00e1nea Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo &#8212; Red Mediterr\u00e1nea\" \/>\n<meta property=\"og:description\" content=\"Red Mediterr\u00e1nea Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/\" \/>\n<meta property=\"og:site_name\" content=\"Red Mediterr\u00e1nea\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redmediterranea.net\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T14:11:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T14:11:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redmediterranea.com\/wp-content\/uploads\/2026\/05\/Cjal-ocanto-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"774\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Red Mediterr\u00e1nea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Red Mediterr\u00e1nea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/\"},\"author\":{\"name\":\"Red Mediterr\u00e1nea\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/person\\\/a59f6085115b75a865fb0338fe81d577\"},\"headline\":\"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo\",\"datePublished\":\"2026-05-08T14:11:40+00:00\",\"dateModified\":\"2026-05-08T14:11:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/\"},\"wordCount\":26,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cjal-ocanto-1.png\",\"keywords\":[\"Concejo Deliberante\",\"De\u00e1n Funes\"],\"articleSection\":[\"Locales\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/\",\"name\":\"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo &#8212; Red Mediterr\u00e1nea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cjal-ocanto-1.png\",\"datePublished\":\"2026-05-08T14:11:40+00:00\",\"dateModified\":\"2026-05-08T14:11:41+00:00\",\"description\":\"Red Mediterr\u00e1nea Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cjal-ocanto-1.png\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cjal-ocanto-1.png\",\"width\":774,\"height\":434},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2026\\\/05\\\/08\\\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/redmediterranea.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#website\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/\",\"name\":\"Red Mediterr\u00e1nea\",\"description\":\"Noticias de De\u00e1n Funes\",\"publisher\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redmediterranea.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\",\"name\":\"Red Mediterr\u00e1nea\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/red.png\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/red.png\",\"width\":400,\"height\":260,\"caption\":\"Red Mediterr\u00e1nea\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redmediterranea.net\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvm4ojIMOGKnk5v9TsWnFWQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/person\\\/a59f6085115b75a865fb0338fe81d577\",\"name\":\"Red Mediterr\u00e1nea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1783885124\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1783885124\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1783885124\",\"caption\":\"Red Mediterr\u00e1nea\"},\"sameAs\":[\"http:\\\/\\\/redmediterranea.com\"],\"url\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/author\\\/hg-hatecraft\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo &#8212; Red Mediterr\u00e1nea","description":"Red Mediterr\u00e1nea Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/","og_locale":"es_ES","og_type":"article","og_title":"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo &#8212; Red Mediterr\u00e1nea","og_description":"Red Mediterr\u00e1nea Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo","og_url":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/","og_site_name":"Red Mediterr\u00e1nea","article_publisher":"https:\/\/www.facebook.com\/redmediterranea.net","article_published_time":"2026-05-08T14:11:40+00:00","article_modified_time":"2026-05-08T14:11:41+00:00","og_image":[{"width":774,"height":434,"url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2026\/05\/Cjal-ocanto-1.png","type":"image\/png"}],"author":"Red Mediterr\u00e1nea","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Red Mediterr\u00e1nea","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/#article","isPartOf":{"@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/"},"author":{"name":"Red Mediterr\u00e1nea","@id":"https:\/\/redmediterranea.com\/#\/schema\/person\/a59f6085115b75a865fb0338fe81d577"},"headline":"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo","datePublished":"2026-05-08T14:11:40+00:00","dateModified":"2026-05-08T14:11:41+00:00","mainEntityOfPage":{"@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/"},"wordCount":26,"commentCount":0,"publisher":{"@id":"https:\/\/redmediterranea.com\/#organization"},"image":{"@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/#primaryimage"},"thumbnailUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2026\/05\/Cjal-ocanto-1.png","keywords":["Concejo Deliberante","De\u00e1n Funes"],"articleSection":["Locales","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/","url":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/","name":"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo &#8212; Red Mediterr\u00e1nea","isPartOf":{"@id":"https:\/\/redmediterranea.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/#primaryimage"},"image":{"@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/#primaryimage"},"thumbnailUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2026\/05\/Cjal-ocanto-1.png","datePublished":"2026-05-08T14:11:40+00:00","dateModified":"2026-05-08T14:11:41+00:00","description":"Red Mediterr\u00e1nea Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo","breadcrumb":{"@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/#primaryimage","url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2026\/05\/Cjal-ocanto-1.png","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2026\/05\/Cjal-ocanto-1.png","width":774,"height":434},{"@type":"BreadcrumbList","@id":"https:\/\/redmediterranea.com\/index.php\/2026\/05\/08\/cjal-javier-ocanto-area-de-salud-el-y-la-dra-colome-se-resistian-a-que-ella-tenga-el-cargo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/redmediterranea.com\/"},{"@type":"ListItem","position":2,"name":"Cjal. Javier Ocanto (\u00c1rea de salud) El y la Dra. Colom\u00e9 se resist\u00edan a que ella tenga el cargo"}]},{"@type":"WebSite","@id":"https:\/\/redmediterranea.com\/#website","url":"https:\/\/redmediterranea.com\/","name":"Red Mediterr\u00e1nea","description":"Noticias de De\u00e1n Funes","publisher":{"@id":"https:\/\/redmediterranea.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redmediterranea.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/redmediterranea.com\/#organization","name":"Red Mediterr\u00e1nea","url":"https:\/\/redmediterranea.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/#\/schema\/logo\/image\/","url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2021\/09\/red.png","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2021\/09\/red.png","width":400,"height":260,"caption":"Red Mediterr\u00e1nea"},"image":{"@id":"https:\/\/redmediterranea.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redmediterranea.net","https:\/\/www.youtube.com\/channel\/UCvm4ojIMOGKnk5v9TsWnFWQ"]},{"@type":"Person","@id":"https:\/\/redmediterranea.com\/#\/schema\/person\/a59f6085115b75a865fb0338fe81d577","name":"Red Mediterr\u00e1nea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1783885124","url":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1783885124","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1783885124","caption":"Red Mediterr\u00e1nea"},"sameAs":["http:\/\/redmediterranea.com"],"url":"https:\/\/redmediterranea.com\/index.php\/author\/hg-hatecraft\/"}]}},"_links":{"self":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/17008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/comments?post=17008"}],"version-history":[{"count":1,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/17008\/revisions"}],"predecessor-version":[{"id":17010,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/17008\/revisions\/17010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/media\/17009"}],"wp:attachment":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/media?parent=17008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/categories?post=17008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/tags?post=17008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}