{"id":15605,"date":"2025-11-25T18:07:49","date_gmt":"2025-11-25T18:07:49","guid":{"rendered":"https:\/\/redmediterranea.com\/?p=15605"},"modified":"2025-11-25T18:07:58","modified_gmt":"2025-11-25T18:07:58","slug":"obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio","status":"publish","type":"post","link":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/","title":{"rendered":"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><\/ul>\n\n\n\n<p>La Municipalidad de Quilino, a trav\u00e9s del \u00e1rea de Obras P\u00fablicas, llev\u00f3 adelante diversas intervenciones luego de las precipitaciones registradas en la regi\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/quilino.gob.ar\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-23-at-16.29.57-300x240.jpeg\" alt=\"\" class=\"wp-image-4054\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/quilino.gob.ar\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-23-at-16.30.37-300x240.jpeg\" alt=\"\" class=\"wp-image-4056\"\/><\/figure>\n\n\n\n<p>En la zona urbana de Quilino, el equipo municipal ejecut\u00f3 trabajos de poda y retiro de \u00e1rboles ca\u00eddos, con el objetivo de garantizar la seguridad de los vecinos y evitar obstrucciones en la v\u00eda p\u00fablica.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/quilino.gob.ar\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-23-at-16.29.46-300x240.jpeg\" alt=\"\" class=\"wp-image-4057\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/quilino.gob.ar\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-23-at-16.29.55-300x240.jpeg\" alt=\"\" class=\"wp-image-4055\"\/><\/figure>\n\n\n\n<p>De manera simult\u00e1nea, se realizaron tareas de reparaci\u00f3n en los caminos de Isla de San Antonio, los cuales hab\u00edan quedado temporalmente incomunicados debido a las condiciones clim\u00e1ticas. Las labores permitieron restablecer la transitabilidad y asegurar el acceso de los habitantes del paraje.<\/p>\n\n\n\n<p>Estas acciones forman parte del trabajo permanente del municipio para mantener en condiciones los espacios p\u00fablicos y asegurar la conectividad de las distintas comunidades de la jurisdicci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Quilino, a trav\u00e9s del \u00e1rea de Obras P\u00fablicas, llev\u00f3 adelante diversas intervenciones luego de las precipitaciones registradas en la regi\u00f3n. En la zona urbana de Quilino, el equipo municipal ejecut\u00f3 trabajos de poda y retiro de \u00e1rboles ca\u00eddos, con el objetivo de garantizar la seguridad de los vecinos y evitar obstrucciones en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[4089,2652,15,16],"class_list":{"0":"post-15605","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-quilino","8":"tag-isla-de-san-antonio","9":"tag-lluvias","10":"tag-mabel-godoy","11":"tag-quilino"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio &#8212; Red Mediterr\u00e1nea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio &#8212; Red Mediterr\u00e1nea\" \/>\n<meta property=\"og:description\" content=\"La Municipalidad de Quilino, a trav\u00e9s del \u00e1rea de Obras P\u00fablicas, llev\u00f3 adelante diversas intervenciones luego de las precipitaciones registradas en la regi\u00f3n. En la zona urbana de Quilino, el equipo municipal ejecut\u00f3 trabajos de poda y retiro de \u00e1rboles ca\u00eddos, con el objetivo de garantizar la seguridad de los vecinos y evitar obstrucciones en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/\" \/>\n<meta property=\"og:site_name\" content=\"Red Mediterr\u00e1nea\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redmediterranea.net\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-25T18:07:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T18:07:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redmediterranea.com\/wp-content\/uploads\/2025\/11\/machine.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Red Mediterr\u00e1nea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Red Mediterr\u00e1nea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/\"},\"author\":{\"name\":\"Red Mediterr\u00e1nea\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/person\\\/a59f6085115b75a865fb0338fe81d577\"},\"headline\":\"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio\",\"datePublished\":\"2025-11-25T18:07:49+00:00\",\"dateModified\":\"2025-11-25T18:07:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/\"},\"wordCount\":160,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/machine.jpeg\",\"keywords\":[\"Isla de San Antonio\",\"Lluvias\",\"Mabel Godoy\",\"Quilino\"],\"articleSection\":[\"Quilino\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/\",\"name\":\"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio &#8212; Red Mediterr\u00e1nea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/machine.jpeg\",\"datePublished\":\"2025-11-25T18:07:49+00:00\",\"dateModified\":\"2025-11-25T18:07:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/machine.jpeg\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/machine.jpeg\",\"width\":590,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2025\\\/11\\\/25\\\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/redmediterranea.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#website\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/\",\"name\":\"Red Mediterr\u00e1nea\",\"description\":\"Noticias de De\u00e1n Funes\",\"publisher\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redmediterranea.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\",\"name\":\"Red Mediterr\u00e1nea\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/red.png\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/red.png\",\"width\":400,\"height\":260,\"caption\":\"Red Mediterr\u00e1nea\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redmediterranea.net\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvm4ojIMOGKnk5v9TsWnFWQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/person\\\/a59f6085115b75a865fb0338fe81d577\",\"name\":\"Red Mediterr\u00e1nea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340\",\"caption\":\"Red Mediterr\u00e1nea\"},\"sameAs\":[\"http:\\\/\\\/redmediterranea.com\"],\"url\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/author\\\/hg-hatecraft\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio &#8212; Red Mediterr\u00e1nea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/","og_locale":"es_ES","og_type":"article","og_title":"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio &#8212; Red Mediterr\u00e1nea","og_description":"La Municipalidad de Quilino, a trav\u00e9s del \u00e1rea de Obras P\u00fablicas, llev\u00f3 adelante diversas intervenciones luego de las precipitaciones registradas en la regi\u00f3n. En la zona urbana de Quilino, el equipo municipal ejecut\u00f3 trabajos de poda y retiro de \u00e1rboles ca\u00eddos, con el objetivo de garantizar la seguridad de los vecinos y evitar obstrucciones en [&hellip;]","og_url":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/","og_site_name":"Red Mediterr\u00e1nea","article_publisher":"https:\/\/www.facebook.com\/redmediterranea.net","article_published_time":"2025-11-25T18:07:49+00:00","article_modified_time":"2025-11-25T18:07:58+00:00","og_image":[{"width":590,"height":472,"url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2025\/11\/machine.jpeg","type":"image\/jpeg"}],"author":"Red Mediterr\u00e1nea","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Red Mediterr\u00e1nea","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/#article","isPartOf":{"@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/"},"author":{"name":"Red Mediterr\u00e1nea","@id":"https:\/\/redmediterranea.com\/#\/schema\/person\/a59f6085115b75a865fb0338fe81d577"},"headline":"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio","datePublished":"2025-11-25T18:07:49+00:00","dateModified":"2025-11-25T18:07:58+00:00","mainEntityOfPage":{"@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/"},"wordCount":160,"commentCount":0,"publisher":{"@id":"https:\/\/redmediterranea.com\/#organization"},"image":{"@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/#primaryimage"},"thumbnailUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2025\/11\/machine.jpeg","keywords":["Isla de San Antonio","Lluvias","Mabel Godoy","Quilino"],"articleSection":["Quilino"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/","url":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/","name":"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio &#8212; Red Mediterr\u00e1nea","isPartOf":{"@id":"https:\/\/redmediterranea.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/#primaryimage"},"image":{"@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/#primaryimage"},"thumbnailUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2025\/11\/machine.jpeg","datePublished":"2025-11-25T18:07:49+00:00","dateModified":"2025-11-25T18:07:58+00:00","breadcrumb":{"@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/#primaryimage","url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2025\/11\/machine.jpeg","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2025\/11\/machine.jpeg","width":590,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/redmediterranea.com\/index.php\/2025\/11\/25\/obras-publicas-realizo-tareas-de-despeje-y-reparacion-tras-las-lluvias-en-quilino-y-en-isla-de-san-antonio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/redmediterranea.com\/"},{"@type":"ListItem","position":2,"name":"Obras P\u00fablicas realiz\u00f3 tareas de despeje y reparaci\u00f3n tras las lluvias en Quilino y en Isla de San Antonio"}]},{"@type":"WebSite","@id":"https:\/\/redmediterranea.com\/#website","url":"https:\/\/redmediterranea.com\/","name":"Red Mediterr\u00e1nea","description":"Noticias de De\u00e1n Funes","publisher":{"@id":"https:\/\/redmediterranea.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redmediterranea.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/redmediterranea.com\/#organization","name":"Red Mediterr\u00e1nea","url":"https:\/\/redmediterranea.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/#\/schema\/logo\/image\/","url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2021\/09\/red.png","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2021\/09\/red.png","width":400,"height":260,"caption":"Red Mediterr\u00e1nea"},"image":{"@id":"https:\/\/redmediterranea.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redmediterranea.net","https:\/\/www.youtube.com\/channel\/UCvm4ojIMOGKnk5v9TsWnFWQ"]},{"@type":"Person","@id":"https:\/\/redmediterranea.com\/#\/schema\/person\/a59f6085115b75a865fb0338fe81d577","name":"Red Mediterr\u00e1nea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340","url":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340","caption":"Red Mediterr\u00e1nea"},"sameAs":["http:\/\/redmediterranea.com"],"url":"https:\/\/redmediterranea.com\/index.php\/author\/hg-hatecraft\/"}]}},"_links":{"self":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/15605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/comments?post=15605"}],"version-history":[{"count":1,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/15605\/revisions"}],"predecessor-version":[{"id":15607,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/15605\/revisions\/15607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/media\/15606"}],"wp:attachment":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/media?parent=15605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/categories?post=15605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/tags?post=15605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}