{"id":10024,"date":"2024-03-07T23:14:46","date_gmt":"2024-03-07T23:14:46","guid":{"rendered":"https:\/\/redmediterranea.com\/?p=10024"},"modified":"2024-03-07T23:14:47","modified_gmt":"2024-03-07T23:14:47","slug":"la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia","status":"publish","type":"post","link":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/","title":{"rendered":"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia"},"content":{"rendered":"\n<p>La Asamblea Provincial reunida este jueves 7 de marzo, dando continuidad al cuarto intermedio votado en la \u00faltima asamblea, y ante la falta de una propuesta de aumento salarial por parte del Gobierno, resolvi\u00f3 por mayor\u00eda:&nbsp;<\/p>\n\n\n\n<p><strong>&#8211; Realizar acciones a contraturno, de acuerdo a la modalidad que determine cada Departamento, desde el lunes 11 al mi\u00e9rcoles 13 de marzo.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>&#8211; Realizar un paro de 24 horas con acciones en cada territorio el jueves 14 de marzo.<\/strong><\/p>\n\n\n\n<p>&#8211; En caso de no haber una propuesta salarial, el lunes 18 de marzo llevar adelante asambleas de una hora por turno en las escuelas, para seguir debatiendo las acciones a seguir.&nbsp;<\/p>\n\n\n\n<p>&#8211; De existir una nueva propuesta salarial, suspender las acciones y medidas, y habilitar los mecanismos de consulta del sindicato.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, las y los delegados departamentales resolvieron ratificar las demandas expuestas en la asamblea provincial del 28 de febrero:&nbsp;<\/p>\n\n\n\n<p>&#8211; Exigir que se cumpla la paritaria del 2023.&nbsp;<\/p>\n\n\n\n<p>&#8211; Instar a que se complete la titularizaci\u00f3n de las y los compa\u00f1eros de PIT, PROA, Coordinaciones de Curso y Nivel Superior. &#8211; Ante la diversidad de problemas edilicios, funcionales y\/o de infraestructura exigir que el Gobierno provincial cumpla con los planes de infraestructura de manera inmediata.&nbsp;<\/p>\n\n\n\n<p>&#8211; Mantener la eliminaci\u00f3n de los art\u00edculos 3 y 4 de la resoluci\u00f3n 07\/2024 referida al \u00edtem \u201cProfesionalidad Docente\u00bb.&nbsp;<\/p>\n\n\n\n<p>&#8211; Exigir la mejora inmediata de los servicios de APROSS en toda la provincia de C\u00f3rdoba.<\/p>\n\n\n\n<p>En cuanto a la ley 10.694 exigir:&nbsp;<\/p>\n\n\n\n<p>&#8211; La eliminaci\u00f3n del diferimiento de las y los compa\u00f1eros jubilados.&nbsp;<\/p>\n\n\n\n<p>&#8211; El cumplimiento del Fallo Bossio (pago del 82% m\u00f3vil).&nbsp;<\/p>\n\n\n\n<p>&#8211; La eliminaci\u00f3n del descuento por doble beneficio.&nbsp;<\/p>\n\n\n\n<p>Por \u00faltimo, en el plano nacional exigir:&nbsp;<\/p>\n\n\n\n<p>&#8211; Devoluci\u00f3n del Fondo Nacional de Incentivo Docente.&nbsp;<\/p>\n\n\n\n<p>&#8211; Devoluci\u00f3n del Fondo Compensador.&nbsp;<\/p>\n\n\n\n<p>&#8211; Convocatoria a paritarias nacionales.&nbsp;<\/p>\n\n\n\n<p>&#8211; Sostenimiento de la 5ta. hora y de todos los Programas Nacionales.&nbsp;<\/p>\n\n\n\n<p>Por otra parte, por unanimidad, la Asamblea resolvi\u00f3:&nbsp;<\/p>\n\n\n\n<p>&#8211; Repudiar las declaraciones del presidente Javier Milei realizadas el mi\u00e9rcoles 6 de marzo en el acto de inauguraci\u00f3n del ciclo lectivo en el establecimiento de gesti\u00f3n privada \u201cCardenal Copello\u00bb de Villa Devoto.&nbsp;<\/p>\n\n\n\n<p>En dicho discurso de m\u00e1s de una hora a estudiantes de este colegio secundario, la m\u00e1xima autoridad del Ejecutivo Nacional se dedic\u00f3 a realizar afirmaciones en t\u00e9rminos peyorativos sobre distintos posicionamientos pol\u00edtico ideol\u00f3gicos (utilizando expresiones tales como \u00abcomunistas\u00bb, \u00absocialistas\u00bb \u00abzurdos\u00bb y \u00abasesinos de pa\u00f1uelos verdes\u00bb). Adem\u00e1s hizo apolog\u00eda a la violaci\u00f3n.<\/p>\n\n\n\n<p>Adem\u00e1s, el presidente afirm\u00f3: \u00ablos j\u00f3venes llevan menos tiempo expuestos al mecanismo de lavado de cerebro que es la educaci\u00f3n p\u00fablica, independientemente de que sea de gesti\u00f3n estatal o privada\u00bb y que \u00ablos contenidos (de la escuela) est\u00e1n recontra rojos\u00bb.&nbsp;<\/p>\n\n\n\n<p>Como UEPC nos pronunciamos en contra de este nuevo ataque hacia la educaci\u00f3n p\u00fablica por parte de un gobierno que, tanto discursiva como pol\u00edtica y econ\u00f3micamente, nos viene golpeando permanentemente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asamblea Provincial reunida este jueves 7 de marzo, dando continuidad al cuarto intermedio votado en la \u00faltima asamblea, y ante la falta de una propuesta de aumento salarial por parte del Gobierno, resolvi\u00f3 por mayor\u00eda:&nbsp; &#8211; Realizar acciones a contraturno, de acuerdo a la modalidad que determine cada Departamento, desde el lunes 11 al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1214,60],"tags":[2825,222,901,610],"class_list":{"0":"post-10024","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales","8":"category-reclamo","9":"category-uepc","10":"tag-14-de-marzo","11":"tag-asamblea","12":"tag-paro","13":"tag-provincia-de-cordoba"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia &#8212; Red Mediterr\u00e1nea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia &#8212; Red Mediterr\u00e1nea\" \/>\n<meta property=\"og:description\" content=\"La Asamblea Provincial reunida este jueves 7 de marzo, dando continuidad al cuarto intermedio votado en la \u00faltima asamblea, y ante la falta de una propuesta de aumento salarial por parte del Gobierno, resolvi\u00f3 por mayor\u00eda:&nbsp; &#8211; Realizar acciones a contraturno, de acuerdo a la modalidad que determine cada Departamento, desde el lunes 11 al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/\" \/>\n<meta property=\"og:site_name\" content=\"Red Mediterr\u00e1nea\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redmediterranea.net\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T23:14:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T23:14:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/redmediterranea.com\/wp-content\/uploads\/2024\/03\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Red Mediterr\u00e1nea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Red Mediterr\u00e1nea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/\"},\"author\":{\"name\":\"Red Mediterr\u00e1nea\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/person\\\/a59f6085115b75a865fb0338fe81d577\"},\"headline\":\"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia\",\"datePublished\":\"2024-03-07T23:14:46+00:00\",\"dateModified\":\"2024-03-07T23:14:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/\"},\"wordCount\":533,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg\",\"keywords\":[\"14 de Marzo\",\"Asamblea\",\"Paro\",\"Provincia de C\u00f3rdoba\"],\"articleSection\":[\"Locales\",\"Reclamo\",\"UEPC\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/\",\"name\":\"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia &#8212; Red Mediterr\u00e1nea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg\",\"datePublished\":\"2024-03-07T23:14:46+00:00\",\"dateModified\":\"2024-03-07T23:14:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/2024\\\/03\\\/07\\\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/redmediterranea.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#website\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/\",\"name\":\"Red Mediterr\u00e1nea\",\"description\":\"Noticias de De\u00e1n Funes\",\"publisher\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redmediterranea.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#organization\",\"name\":\"Red Mediterr\u00e1nea\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/red.png\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/red.png\",\"width\":400,\"height\":260,\"caption\":\"Red Mediterr\u00e1nea\"},\"image\":{\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redmediterranea.net\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvm4ojIMOGKnk5v9TsWnFWQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/#\\\/schema\\\/person\\\/a59f6085115b75a865fb0338fe81d577\",\"name\":\"Red Mediterr\u00e1nea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340\",\"url\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340\",\"contentUrl\":\"https:\\\/\\\/redmediterranea.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340\",\"caption\":\"Red Mediterr\u00e1nea\"},\"sameAs\":[\"http:\\\/\\\/redmediterranea.com\"],\"url\":\"https:\\\/\\\/redmediterranea.com\\\/index.php\\\/author\\\/hg-hatecraft\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia &#8212; Red Mediterr\u00e1nea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/","og_locale":"es_ES","og_type":"article","og_title":"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia &#8212; Red Mediterr\u00e1nea","og_description":"La Asamblea Provincial reunida este jueves 7 de marzo, dando continuidad al cuarto intermedio votado en la \u00faltima asamblea, y ante la falta de una propuesta de aumento salarial por parte del Gobierno, resolvi\u00f3 por mayor\u00eda:&nbsp; &#8211; Realizar acciones a contraturno, de acuerdo a la modalidad que determine cada Departamento, desde el lunes 11 al [&hellip;]","og_url":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/","og_site_name":"Red Mediterr\u00e1nea","article_publisher":"https:\/\/www.facebook.com\/redmediterranea.net","article_published_time":"2024-03-07T23:14:46+00:00","article_modified_time":"2024-03-07T23:14:47+00:00","og_image":[{"width":1600,"height":1200,"url":"http:\/\/redmediterranea.com\/wp-content\/uploads\/2024\/03\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg","type":"image\/jpeg"}],"author":"Red Mediterr\u00e1nea","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Red Mediterr\u00e1nea","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/#article","isPartOf":{"@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/"},"author":{"name":"Red Mediterr\u00e1nea","@id":"https:\/\/redmediterranea.com\/#\/schema\/person\/a59f6085115b75a865fb0338fe81d577"},"headline":"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia","datePublished":"2024-03-07T23:14:46+00:00","dateModified":"2024-03-07T23:14:47+00:00","mainEntityOfPage":{"@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/"},"wordCount":533,"commentCount":0,"publisher":{"@id":"https:\/\/redmediterranea.com\/#organization"},"image":{"@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/#primaryimage"},"thumbnailUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2024\/03\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg","keywords":["14 de Marzo","Asamblea","Paro","Provincia de C\u00f3rdoba"],"articleSection":["Locales","Reclamo","UEPC"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/","url":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/","name":"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia &#8212; Red Mediterr\u00e1nea","isPartOf":{"@id":"https:\/\/redmediterranea.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/#primaryimage"},"image":{"@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/#primaryimage"},"thumbnailUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2024\/03\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg","datePublished":"2024-03-07T23:14:46+00:00","dateModified":"2024-03-07T23:14:47+00:00","breadcrumb":{"@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/#primaryimage","url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2024\/03\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2024\/03\/3186-1639-070324-whatsapp-image-2024-03-07-at-125218.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/redmediterranea.com\/index.php\/2024\/03\/07\/la-asamblea-aprobo-un-paro-por-24-horas-el-14-de-marzo-y-acciones-en-toda-la-provincia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/redmediterranea.com\/"},{"@type":"ListItem","position":2,"name":"La Asamblea aprob\u00f3 un paro por 24 horas el 14 de marzo y acciones en toda la provincia"}]},{"@type":"WebSite","@id":"https:\/\/redmediterranea.com\/#website","url":"https:\/\/redmediterranea.com\/","name":"Red Mediterr\u00e1nea","description":"Noticias de De\u00e1n Funes","publisher":{"@id":"https:\/\/redmediterranea.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redmediterranea.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/redmediterranea.com\/#organization","name":"Red Mediterr\u00e1nea","url":"https:\/\/redmediterranea.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/#\/schema\/logo\/image\/","url":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2021\/09\/red.png","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/uploads\/2021\/09\/red.png","width":400,"height":260,"caption":"Red Mediterr\u00e1nea"},"image":{"@id":"https:\/\/redmediterranea.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redmediterranea.net","https:\/\/www.youtube.com\/channel\/UCvm4ojIMOGKnk5v9TsWnFWQ"]},{"@type":"Person","@id":"https:\/\/redmediterranea.com\/#\/schema\/person\/a59f6085115b75a865fb0338fe81d577","name":"Red Mediterr\u00e1nea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340","url":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340","contentUrl":"https:\/\/redmediterranea.com\/wp-content\/litespeed\/avatar\/1a3770c806a5dd31cb05580dd57bedd6.jpg?ver=1778441340","caption":"Red Mediterr\u00e1nea"},"sameAs":["http:\/\/redmediterranea.com"],"url":"https:\/\/redmediterranea.com\/index.php\/author\/hg-hatecraft\/"}]}},"_links":{"self":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/10024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/comments?post=10024"}],"version-history":[{"count":1,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/10024\/revisions"}],"predecessor-version":[{"id":10026,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/posts\/10024\/revisions\/10026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/media\/10025"}],"wp:attachment":[{"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/media?parent=10024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/categories?post=10024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redmediterranea.com\/index.php\/wp-json\/wp\/v2\/tags?post=10024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}